{"id":773,"date":"2016-09-19T03:28:56","date_gmt":"2016-09-19T03:28:56","guid":{"rendered":"http:\/\/www.clearsoundatlanta.com\/blog\/?p=773"},"modified":"2016-12-08T03:29:22","modified_gmt":"2016-12-08T03:29:22","slug":"topping-off-party-with-batson-cook-construction","status":"publish","type":"post","link":"https:\/\/clearsoundatlanta.com\/blog\/topping-off-party-with-batson-cook-construction\/","title":{"rendered":"Topping Off Party with Batson Cook Construction"},"content":{"rendered":"<p><a href=\"http:\/\/www.clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132747-1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132747-1-300x169.jpg\" alt=\"20160909_132747-1\" width=\"300\" height=\"169\" class=\"alignleft size-medium wp-image-774\" srcset=\"https:\/\/clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132747-1-300x169.jpg 300w, https:\/\/clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132747-1-768x432.jpg 768w, https:\/\/clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132747-1-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132404-1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132404-1-300x169.jpg\" alt=\"20160909_132404-1\" width=\"300\" height=\"169\" class=\"alignleft size-medium wp-image-775\" srcset=\"https:\/\/clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132404-1-300x169.jpg 300w, https:\/\/clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132404-1-768x432.jpg 768w, https:\/\/clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132404-1-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132355.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132355-300x169.jpg\" alt=\"20160909_132355\" width=\"300\" height=\"169\" class=\"alignleft size-medium wp-image-776\" srcset=\"https:\/\/clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132355-300x169.jpg 300w, https:\/\/clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132355-768x432.jpg 768w, https:\/\/clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132355-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132350.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132350-300x169.jpg\" alt=\"20160909_132350\" width=\"300\" height=\"169\" class=\"alignleft size-medium wp-image-777\" srcset=\"https:\/\/clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132350-300x169.jpg 300w, https:\/\/clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132350-768x432.jpg 768w, https:\/\/clearsoundatlanta.com\/blog\/wp-content\/uploads\/2016\/12\/20160909_132350-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-773","post","type-post","status-publish","format-standard","hentry","category-audio-equipment"],"gutentor_comment":0,"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-thumbnail":false},"uagb_author_info":{"display_name":"Norris Wooten","author_link":"https:\/\/clearsoundatlanta.com\/blog\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/clearsoundatlanta.com\/blog\/wp-json\/wp\/v2\/posts\/773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clearsoundatlanta.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clearsoundatlanta.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clearsoundatlanta.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clearsoundatlanta.com\/blog\/wp-json\/wp\/v2\/comments?post=773"}],"version-history":[{"count":1,"href":"https:\/\/clearsoundatlanta.com\/blog\/wp-json\/wp\/v2\/posts\/773\/revisions"}],"predecessor-version":[{"id":778,"href":"https:\/\/clearsoundatlanta.com\/blog\/wp-json\/wp\/v2\/posts\/773\/revisions\/778"}],"wp:attachment":[{"href":"https:\/\/clearsoundatlanta.com\/blog\/wp-json\/wp\/v2\/media?parent=773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clearsoundatlanta.com\/blog\/wp-json\/wp\/v2\/categories?post=773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clearsoundatlanta.com\/blog\/wp-json\/wp\/v2\/tags?post=773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}