{"id":29,"count":1,"description":"","link":"https:\/\/clearsoundatlanta.com\/blog\/tag\/first-lady-sandra-deal\/","name":"First Lady Sandra Deal","slug":"first-lady-sandra-deal","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/clearsoundatlanta.com\/blog\/wp-json\/wp\/v2\/tags\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clearsoundatlanta.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/clearsoundatlanta.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/clearsoundatlanta.com\/blog\/wp-json\/wp\/v2\/posts?tags=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}